{"id":578,"count":0,"description":"","link":"https:\/\/euroexperts.org\/de\/category\/buchpraesentation","name":"Buchpr\u00e4sentation","slug":"buchpraesentation","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/euroexperts.org\/de\/wp-json\/wp\/v2\/categories\/578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euroexperts.org\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/euroexperts.org\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/euroexperts.org\/de\/wp-json\/wp\/v2\/posts?categories=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}